{"id":988,"count":12,"description":"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden. Einfache Routen f\u00fcr jedermann geeignet, auch f\u00fcr Familien.","link":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/","name":"Ausfl\u00fcge: Touristisch","slug":"ausfluge-touristisch","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Einfache Ausfl\u00fcge auf den \u00c4tna?<\/title>\n<meta name=\"description\" content=\"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden.Einfache Routen f\u00fcr jedermann geeignet\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Einfache Ausfl\u00fcge auf den \u00c4tna?\" \/>\n<meta property=\"og:description\" content=\"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden.Einfache Routen f\u00fcr jedermann geeignet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/\" \/>\n<meta property=\"og:site_name\" content=\"Guide Vulcanologiche Etna Nord\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/category\\\/ausfluge-touristisch\\\/\",\"url\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/category\\\/ausfluge-touristisch\\\/\",\"name\":\"Einfache Ausfl\u00fcge auf den \u00c4tna?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/#website\"},\"description\":\"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden.Einfache Routen f\u00fcr jedermann geeignet\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/category\\\/ausfluge-touristisch\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/category\\\/ausfluge-touristisch\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausfl\u00fcge: Touristisch\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/\",\"name\":\"Guide Vulcanologiche Etna Nord\",\"description\":\"Guide Etna Abilitate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/guidevulcanologicheetna.it\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Einfache Ausfl\u00fcge auf den \u00c4tna?","description":"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden.Einfache Routen f\u00fcr jedermann geeignet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/","og_locale":"de_DE","og_type":"article","og_title":"Einfache Ausfl\u00fcge auf den \u00c4tna?","og_description":"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden.Einfache Routen f\u00fcr jedermann geeignet","og_url":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/","og_site_name":"Guide Vulcanologiche Etna Nord","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/","url":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/","name":"Einfache Ausfl\u00fcge auf den \u00c4tna?","isPartOf":{"@id":"https:\/\/guidevulcanologicheetna.it\/de\/#website"},"description":"Einfache Ausfl\u00fcge auf den \u00c4tna?. Buchen Sie die besten gef\u00fchrten Touren, die von den Guides f\u00fcr Sie ausgew\u00e4hlt wurden.Einfache Routen f\u00fcr jedermann geeignet","breadcrumb":{"@id":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/guidevulcanologicheetna.it\/de\/category\/ausfluge-touristisch\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/guidevulcanologicheetna.it\/de\/"},{"@type":"ListItem","position":2,"name":"Ausfl\u00fcge: Touristisch"}]},{"@type":"WebSite","@id":"https:\/\/guidevulcanologicheetna.it\/de\/#website","url":"https:\/\/guidevulcanologicheetna.it\/de\/","name":"Guide Vulcanologiche Etna Nord","description":"Guide Etna Abilitate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/guidevulcanologicheetna.it\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/guidevulcanologicheetna.it\/de\/wp-json\/wp\/v2\/categories\/988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/guidevulcanologicheetna.it\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/guidevulcanologicheetna.it\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/guidevulcanologicheetna.it\/de\/wp-json\/wp\/v2\/posts?categories=988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}